{"id":2656,"date":"2022-04-20T13:39:13","date_gmt":"2022-04-20T11:39:13","guid":{"rendered":"https:\/\/www.unspendr.com\/marcas\/brands\/agape-studio\/"},"modified":"2023-09-21T18:20:10","modified_gmt":"2023-09-21T16:20:10","slug":"agape-studio","status":"publish","type":"unspendr_bra_dir_ltg","link":"https:\/\/www.unspendr.com\/es\/marcas\/brands\/agape-studio\/","title":{"rendered":"Agap\u00e9 Studio"},"author":0,"comment_status":"closed","ping_status":"closed","template":"","class_list":{"0":"post-2656","1":"unspendr_bra_dir_ltg","2":"type-unspendr_bra_dir_ltg","3":"status-publish","5":"unspendr_bra_dir_cat-zapatos-complementos-es","6":"unspendr_bra_dir_tag-regalo-ecologico","7":"unspendr_bra_dir_tag-sostenible"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v21.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Agap\u00e9 Studio &#8211; Unspendr Beta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unspendr.com\/es\/marcas\/brands\/agape-studio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agap\u00e9 Studio\" \/>\n<meta property=\"og:description\" content=\"Agap\u00e9 Studio es una marca de joyas con base en Par\u00eds. Todos sus productos est\u00e1n ba\u00f1ados en oro sostenible, se hacen a mano y con procesos artesanos. En a\u00f1adido, las bolsas en que son entregados los productos son de cuero vegano y las cajas de cart\u00f3n reciclado. A lo largo de todo el proceso de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unspendr.com\/es\/marcas\/brands\/agape-studio\/\" \/>\n<meta property=\"og:site_name\" content=\"Unspendr Beta\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unspendr\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-21T16:20:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.unspendr.com\/es\/marcas\/brands\/agape-studio\/\",\"url\":\"https:\/\/www.unspendr.com\/es\/marcas\/brands\/agape-studio\/\",\"name\":\"Agap\u00e9 Studio &#8211; Unspendr Beta\",\"isPartOf\":{\"@id\":\"https:\/\/www.unspendr.com\/#website\"},\"datePublished\":\"2022-04-20T11:39:13+00:00\",\"dateModified\":\"2023-09-21T16:20:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.unspendr.com\/es\/marcas\/brands\/agape-studio\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.unspendr.com\/es\/marcas\/brands\/agape-studio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.unspendr.com\/es\/marcas\/brands\/agape-studio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.unspendr.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zapatos y complementos\",\"item\":\"https:\/\/www.unspendr.com\/es\/marcas\/categories\/zapatos-complementos-es\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Agap\u00e9 Studio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.unspendr.com\/#website\",\"url\":\"https:\/\/www.unspendr.com\/\",\"name\":\"Unspendr Beta\",\"description\":\"Unspendr Beta WP\",\"publisher\":{\"@id\":\"https:\/\/www.unspendr.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.unspendr.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.unspendr.com\/#organization\",\"name\":\"Unspendr\",\"url\":\"https:\/\/www.unspendr.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.unspendr.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.unspendr.com\/wp-content\/uploads\/2022\/05\/UNSPENDR_LOGO.png\",\"contentUrl\":\"https:\/\/www.unspendr.com\/wp-content\/uploads\/2022\/05\/UNSPENDR_LOGO.png\",\"width\":1971,\"height\":584,\"caption\":\"Unspendr\"},\"image\":{\"@id\":\"https:\/\/www.unspendr.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/unspendr\",\"https:\/\/www.instagram.com\/unspendr\",\"https:\/\/www.linkedin.com\/company\/unspendr\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Agap\u00e9 Studio &#8211; Unspendr Beta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unspendr.com\/es\/marcas\/brands\/agape-studio\/","og_locale":"es_ES","og_type":"article","og_title":"Agap\u00e9 Studio","og_description":"Agap\u00e9 Studio es una marca de joyas con base en Par\u00eds. Todos sus productos est\u00e1n ba\u00f1ados en oro sostenible, se hacen a mano y con procesos artesanos. En a\u00f1adido, las bolsas en que son entregados los productos son de cuero vegano y las cajas de cart\u00f3n reciclado. A lo largo de todo el proceso de [&hellip;]","og_url":"https:\/\/www.unspendr.com\/es\/marcas\/brands\/agape-studio\/","og_site_name":"Unspendr Beta","article_publisher":"https:\/\/www.facebook.com\/unspendr","article_modified_time":"2023-09-21T16:20:10+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unspendr.com\/es\/marcas\/brands\/agape-studio\/","url":"https:\/\/www.unspendr.com\/es\/marcas\/brands\/agape-studio\/","name":"Agap\u00e9 Studio &#8211; Unspendr Beta","isPartOf":{"@id":"https:\/\/www.unspendr.com\/#website"},"datePublished":"2022-04-20T11:39:13+00:00","dateModified":"2023-09-21T16:20:10+00:00","breadcrumb":{"@id":"https:\/\/www.unspendr.com\/es\/marcas\/brands\/agape-studio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unspendr.com\/es\/marcas\/brands\/agape-studio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.unspendr.com\/es\/marcas\/brands\/agape-studio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.unspendr.com\/"},{"@type":"ListItem","position":2,"name":"Zapatos y complementos","item":"https:\/\/www.unspendr.com\/es\/marcas\/categories\/zapatos-complementos-es\/"},{"@type":"ListItem","position":3,"name":"Agap\u00e9 Studio"}]},{"@type":"WebSite","@id":"https:\/\/www.unspendr.com\/#website","url":"https:\/\/www.unspendr.com\/","name":"Unspendr Beta","description":"Unspendr Beta WP","publisher":{"@id":"https:\/\/www.unspendr.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unspendr.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.unspendr.com\/#organization","name":"Unspendr","url":"https:\/\/www.unspendr.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.unspendr.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.unspendr.com\/wp-content\/uploads\/2022\/05\/UNSPENDR_LOGO.png","contentUrl":"https:\/\/www.unspendr.com\/wp-content\/uploads\/2022\/05\/UNSPENDR_LOGO.png","width":1971,"height":584,"caption":"Unspendr"},"image":{"@id":"https:\/\/www.unspendr.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unspendr","https:\/\/www.instagram.com\/unspendr","https:\/\/www.linkedin.com\/company\/unspendr"]}]}},"_links":{"self":[{"href":"https:\/\/www.unspendr.com\/es\/wp-json\/wp\/v2\/unspendr_bra_dir_ltg\/2656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unspendr.com\/es\/wp-json\/wp\/v2\/unspendr_bra_dir_ltg"}],"about":[{"href":"https:\/\/www.unspendr.com\/es\/wp-json\/wp\/v2\/types\/unspendr_bra_dir_ltg"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unspendr.com\/es\/wp-json\/wp\/v2\/comments?post=2656"}],"wp:attachment":[{"href":"https:\/\/www.unspendr.com\/es\/wp-json\/wp\/v2\/media?parent=2656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}